{"id":678,"date":"2023-05-02T22:55:45","date_gmt":"2023-05-03T01:55:45","guid":{"rendered":"https:\/\/dcentro.uy\/dc\/?p=678"},"modified":"2026-08-14T11:10:53","modified_gmt":"2026-08-14T14:10:53","slug":"martin-fernandez","status":"publish","type":"post","link":"https:\/\/dcentro.uy\/dc\/martin-fernandez\/","title":{"rendered":"Mart\u00edn Fern\u00e1ndez"},"content":{"rendered":"<p><strong>Mart\u00edn Fern\u00e1ndez Aizcorbe<\/strong> naci\u00f3 el 5 de Febrero de 1974 en el departamento de Montevideo. Est\u00e1 casado con Irene y tienen un hijo, Francisco, de 7 a\u00f1os.<\/p>\n<p>En el a\u00f1o 1994 integr\u00f3 la lista 903 a la C\u00e1mara de Representantes respaldando la f\u00f3rmula Ramirez-Chiruchi. Un a\u00f1o despu\u00e9s fue electo integrante de la primera Mesa Departamental de J\u00f3venes del Partido Nacional en la cual se desempe\u00f1\u00f3 como Secretario de Asuntos Sociales. En el a\u00f1o 2000 fue electo edil por el Partido Nacional a la Junta Departamental de Montevideo y en julio de ese mismo a\u00f1o fue electo 1er Vicepresidente de la Junta Departamental de Montevideo, la cual presidi\u00f3 en repetidas ocasiones, siendo adem\u00e1s Coordinador de la Bancada Nacional de Ediles del Partido Nacional.<\/p>\n<p>En julio de 2004 fue electo Convencional Nacional y Departamental del Partido Nacional por la Lista 33. Ese mismo a\u00f1o fue proclamado diputado suplente por el Departamento de Montevideo, banca que ejerci\u00f3 en repetidas oportunidades desde julio del 2005, al finalizar su mandato en la Junta Departamental de Montevideo.<\/p>\n<p>Entre el a\u00f1o 2005 y 2012 integra la Comisi\u00f3n Directiva del Club Atl\u00e9tico Cord\u00f3n ocupando varios cargos, entre ellos la vicepresidencia entre 2010 y 2012 y la Presidencia en 2012, a\u00f1o en que ocupa interinamente como neutral la Mesa de la Liga Uruguaya de B\u00e1squetbol.<\/p>\n<p>El 29 de noviembre de 2007 funda, con un importante grupo de compa\u00f1eros provenientes de distintas vertientes de la vida politica y social, la agrupaci\u00f3n \u00abPROYECTO PA\u00cdS\u00bb.<br \/>\nEn las elecciones nacionales de octubre de 2009 fue electo diputado suplente para el per\u00edodo 2010 \u2013 2015.\u00a0 En diciembre de 2011 asumi\u00f3 como Prosecretario de la Camara de Representantes, cargo que deja en junio de 2015 para pasar a desempe\u00f1arse como Secretario de Bancada del sector Alianza Nacional, integrando adem\u00e1s, el Honorable Directorio del Partido Nacional.<\/p>\n<p>En abril de 2020 asume como Presidente del Instituto Nacional de Cooperativismo (INACOOP).<\/p>\n<p><a class=\"twitter-timeline\" href=\"https:\/\/twitter.com\/mfernandez33?ref_src=twsrc%5Etfw\">Tweets by mfernandez33<\/a> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Director del BROU<\/p>\n","protected":false},"author":2,"featured_media":1236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nosotros"],"_links":{"self":[{"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/posts\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/comments?post=678"}],"version-history":[{"count":8,"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/posts\/678\/revisions"}],"predecessor-version":[{"id":1195,"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/posts\/678\/revisions\/1195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/media\/1236"}],"wp:attachment":[{"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/media?parent=678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/categories?post=678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dcentro.uy\/dc\/wp-json\/wp\/v2\/tags?post=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}